{"id":5,"count":4,"description":"","link":"https:\/\/thekiranabali.com\/ungasan\/category\/special-offers\/","name":"Special Offers","slug":"special-offers","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Special Offers Archives - The Kirana Ungasan<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/thekiranabali.com\/ungasan\/category\/special-offers\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Special Offers Archives - The Kirana Ungasan\" \/>\n<meta property=\"og:url\" content=\"https:\/\/thekiranabali.com\/ungasan\/category\/special-offers\/\" \/>\n<meta property=\"og:site_name\" content=\"The Kirana Ungasan\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@kiranaungasan\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/thekiranabali.com\\\/ungasan\\\/category\\\/special-offers\\\/\",\"url\":\"https:\\\/\\\/thekiranabali.com\\\/ungasan\\\/category\\\/special-offers\\\/\",\"name\":\"Special Offers Archives - The Kirana Ungasan\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/thekiranabali.com\\\/ungasan\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/thekiranabali.com\\\/ungasan\\\/category\\\/special-offers\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/thekiranabali.com\\\/ungasan\\\/category\\\/special-offers\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/thekiranabali.com\\\/ungasan\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Special Offers\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/thekiranabali.com\\\/ungasan\\\/#website\",\"url\":\"https:\\\/\\\/thekiranabali.com\\\/ungasan\\\/\",\"name\":\"The Kirana Ungasan\",\"description\":\"The Kirana Ungasan\",\"publisher\":{\"@id\":\"https:\\\/\\\/thekiranabali.com\\\/ungasan\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/thekiranabali.com\\\/ungasan\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/thekiranabali.com\\\/ungasan\\\/#organization\",\"name\":\"The Kirana Ungasan\",\"url\":\"https:\\\/\\\/thekiranabali.com\\\/ungasan\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/thekiranabali.com\\\/ungasan\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/thekiranabali.com\\\/ungasan\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/thekiranabali.com\\\/ungasan\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/logo.png\",\"width\":118,\"height\":100,\"caption\":\"The Kirana Ungasan\"},\"image\":{\"@id\":\"https:\\\/\\\/thekiranabali.com\\\/ungasan\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/business.facebook.com\\\/thekiranaungasan\\\/\",\"https:\\\/\\\/x.com\\\/kiranaungasan\",\"https:\\\/\\\/www.instagram.com\\\/thekiranaungasanbali\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Special Offers Archives - The Kirana Ungasan","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/thekiranabali.com\/ungasan\/category\/special-offers\/","og_locale":"en_US","og_type":"article","og_title":"Special Offers Archives - The Kirana Ungasan","og_url":"https:\/\/thekiranabali.com\/ungasan\/category\/special-offers\/","og_site_name":"The Kirana Ungasan","twitter_card":"summary_large_image","twitter_site":"@kiranaungasan","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/thekiranabali.com\/ungasan\/category\/special-offers\/","url":"https:\/\/thekiranabali.com\/ungasan\/category\/special-offers\/","name":"Special Offers Archives - The Kirana Ungasan","isPartOf":{"@id":"https:\/\/thekiranabali.com\/ungasan\/#website"},"breadcrumb":{"@id":"https:\/\/thekiranabali.com\/ungasan\/category\/special-offers\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/thekiranabali.com\/ungasan\/category\/special-offers\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/thekiranabali.com\/ungasan\/"},{"@type":"ListItem","position":2,"name":"Special Offers"}]},{"@type":"WebSite","@id":"https:\/\/thekiranabali.com\/ungasan\/#website","url":"https:\/\/thekiranabali.com\/ungasan\/","name":"The Kirana Ungasan","description":"The Kirana Ungasan","publisher":{"@id":"https:\/\/thekiranabali.com\/ungasan\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/thekiranabali.com\/ungasan\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/thekiranabali.com\/ungasan\/#organization","name":"The Kirana Ungasan","url":"https:\/\/thekiranabali.com\/ungasan\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/thekiranabali.com\/ungasan\/#\/schema\/logo\/image\/","url":"https:\/\/thekiranabali.com\/ungasan\/wp-content\/uploads\/2018\/12\/logo.png","contentUrl":"https:\/\/thekiranabali.com\/ungasan\/wp-content\/uploads\/2018\/12\/logo.png","width":118,"height":100,"caption":"The Kirana Ungasan"},"image":{"@id":"https:\/\/thekiranabali.com\/ungasan\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/business.facebook.com\/thekiranaungasan\/","https:\/\/x.com\/kiranaungasan","https:\/\/www.instagram.com\/thekiranaungasanbali\/"]}]}},"_links":{"self":[{"href":"https:\/\/thekiranabali.com\/ungasan\/wp-json\/wp\/v2\/categories\/5","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/thekiranabali.com\/ungasan\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/thekiranabali.com\/ungasan\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/thekiranabali.com\/ungasan\/wp-json\/wp\/v2\/posts?categories=5"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}